{"id":40,"count":8,"description":"","link":"https:\/\/www.seed4me.app\/blog\/tag\/netflix\/","name":"Netflix","slug":"netflix","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.seed4me.app\/blog\/wp-json\/wp\/v2\/tags\/40"}],"collection":[{"href":"https:\/\/www.seed4me.app\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.seed4me.app\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.seed4me.app\/blog\/wp-json\/wp\/v2\/posts?tags=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}